{"id":3177,"date":"2021-01-20T15:58:31","date_gmt":"2021-01-20T14:58:31","guid":{"rendered":"https:\/\/www.rossocorsa.es\/?post_type=wpb_portfolio&#038;p=3177"},"modified":"2024-06-10T16:19:05","modified_gmt":"2024-06-10T14:19:05","slug":"ferrari-488-challenge-evo","status":"publish","type":"portfolio","link":"https:\/\/www.rossocorsa.com\/it\/portfolio\/ferrari-488-challenge-evo\/","title":{"rendered":"Ferrari 488 Challenge Evo"},"content":{"rendered":"<p>Avete le carte in regola per scendere in pista? Mettete alla prova le vostre abilit\u00e0 di guida con una delle auto sportive pi\u00f9 belle che abbiate mai visto, la Ferrari 488 Challenge Evo.<\/p>\n<div class=\"row\">\n<p class=\"col-sm-4\">Questa vera auto da corsa \u00e8 un'evoluzione della 488 Challenge, con un kit di potenziamento delle prestazioni che include una struttura pi\u00f9 aerodinamica. Il suo design tagliente e aggressivo risalta ancora di pi\u00f9 grazie alla colorazione Rosso Corsa. Gli interni sono un vero sogno: sedili da corsa spaziosi e un volante da corsa aggiornato per una posizione ottimale delle mani in ogni momento. Non avrete scuse per non avere tutto sotto controllo!<\/p>\n<p class=\"col-sm-4\">Un motore V8 in grado di sviluppare 670 CV \u00e8 il cuore di questo Challenge Evo: sia la potenza che il suono sono fuori dal mondo!<\/p>\n<p class=\"col-sm-4\">Ora \u00e8 possibile trovare questa spettacolare Ferrari 488 Challenge Evo presso Rosso Corsa Marbella. Non esitate a contattarci per ulteriori informazioni.<\/p>\n<p class=\"col-sm-4\"><strong>Rosso Corsa Marbella non \u00e8 responsabile degli annunci pubblicati.<\/strong><\/p>\n<p data-pm-slice=\"1 1 []\"><strong>Specifiche<\/strong><\/p>\n<p>\u2022 ESTERNO: Rosso Corsa<\/p>\n<p>\u2022 Sedili da corsa neri<\/p>\n<p>\u2022 ABS<\/p>\n<p>\u2022 Cinture di sicurezza a quattro punti Rosso<\/p>\n<p>\u2022 Volante multifunzione<\/p>\n<p>\u2022 Pinze freno grigie<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il mio nome \u00e8 Evita<\/p>","protected":false},"featured_media":8530,"template":"","meta":[],"automobile":[23],"features":[],"class_list":["post-3177","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","automobile-23"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/portfolio\/3177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/media\/8530"}],"wp:attachment":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/media?parent=3177"}],"wp:term":[{"taxonomy":"automobile","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/automobile?post=3177"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/features?post=3177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}