{"id":3150,"date":"2022-12-29T17:14:54","date_gmt":"2022-12-29T16:14:54","guid":{"rendered":"https:\/\/www.rossocorsa.es\/?post_type=wpb_portfolio&#038;p=3150"},"modified":"2024-05-02T12:44:58","modified_gmt":"2024-05-02T10:44:58","slug":"ferrari-mondial-t","status":"publish","type":"portfolio","link":"https:\/\/www.rossocorsa.com\/it\/portfolio\/ferrari-mondial-t\/","title":{"rendered":"Ferrari Mondial T Cabrio"},"content":{"rendered":"<div class=\"col-sm-12\">\n<p><strong>Siamo entusiasti di dare il benvenuto a questa fantastica Mondial T cabrio su Rosso Corsa!<\/strong> \u00a0Una Ferrari retr\u00f2 che attira tutti gli sguardi ed \u00e8 ora disponibile nel nostro showroom di Marbella.<\/p>\n<p>Questa 2+2 disegnata da Pininfarina \u00e8 stata presentata nel 1989 e, tra le novit\u00e0 che presenta rispetto alla sua versione precedente, c'\u00e8 un motore accoppiato ad un cambio trasversale - da qui la lettera \"T\" nel suo nome.<\/p>\n<p>Il suo aspetto sorprendente \u00e8 caratterizzato da linee spigolose e forme ampie. L'esterno \u00e8 verniciato in un classico Rosso Corsa che si fonde perfettamente con gli interni in pelle beige chiaro.<\/p>\n<p>Sebbene la pi\u00f9 grande attrazione di questa versione sia che \u00e8 una decappottabile, include anche un cappuccio nero che ti permetter\u00e0 di godertela tutto l'anno.<\/p>\n<p><strong>Questa Ferrari Mondial T \u00e8 immatricolata in SPAGNA.<\/strong><\/p>\n<p data-pm-slice=\"1 1 []\"><strong>Specifiche<\/strong><\/p>\n<p>\u2022 ESTERNO: Rosso Corsa<\/p>\n<p>\u2022 INTERNI: Pelle beige<\/p>\n<p>\u2022 TAPPETI: nero<\/p>\n<p>\u2022 LOGO Logo laterale parafango<\/p>\n<p>\u2022 Cavallino Rampante Argento<\/p>\n<p>\u2022 Logo Pininfarina<\/p>\n<p>\u2022 Logo Ferrari<\/p>\n<p>\u2022 Capote nera<\/p>\n<p>\u2022 Contagiri nero<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il mio nome \u00e8 Tania <\/p>","protected":false},"featured_media":8424,"template":"","meta":[],"automobile":[39],"features":[],"class_list":["post-3150","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","automobile-mondial"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/portfolio\/3150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/media\/8424"}],"wp:attachment":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/media?parent=3150"}],"wp:term":[{"taxonomy":"automobile","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/automobile?post=3150"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/features?post=3150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}