{"id":12990,"date":"2023-10-22T15:59:39","date_gmt":"2023-10-22T13:59:39","guid":{"rendered":"https:\/\/www.rossocorsa.com\/?post_type=portfolio&#038;p=12990"},"modified":"2026-03-17T17:44:16","modified_gmt":"2026-03-17T16:44:16","slug":"ferrari-sf90-spider-4","status":"publish","type":"portfolio","link":"https:\/\/www.rossocorsa.com\/it\/portfolio\/ferrari-sf90-spider-4\/","title":{"rendered":"Ferrari SF90 Spider"},"content":{"rendered":"<p data-start=\"149\" data-end=\"336\">\u00c8 arrivata la Ferrari SF90 Spider, potente, bella e costruita per il futuro. \u00c8 la prima spider ibrida plug-in della Ferrari e offre ben 1.000 CV di prestazioni pure.<\/p>\n<p data-start=\"338\" data-end=\"472\">Questa straordinaria SF90 Spider presenta un elegante esterno nero stellato e un interno in pelle bianca 153108, una combinazione audace ed elegante.<\/p>\n<p data-start=\"474\" data-end=\"611\">\u00c8 inoltre dotata di pinze dei freni gialle, scudi Scuderia Ferrari su entrambi i lati e il caratteristico volante multifunzione Ferrari.<\/p>\n<p data-start=\"613\" data-end=\"747\">Quest'auto \u00e8 tutta innovazione, velocit\u00e0 e stile. Un vero capolavoro per chi ama la guida e vuole qualcosa di veramente speciale.<\/p>\n<p data-start=\"749\" data-end=\"823\">Non perdete l'occasione di possedere una delle supercar pi\u00f9 avanzate mai realizzate.<\/p>\n<p data-start=\"749\" data-end=\"823\"><strong>*PREZZO NETTO*<\/strong><\/p>\n<p data-start=\"749\" data-end=\"823\"><strong>SPECIFICHE:<\/strong><\/p>\n<p data-start=\"749\" data-end=\"823\">ESTERNO: ExtraRange<\/p>\n<p data-start=\"749\" data-end=\"823\">INTERNO: ExtraRange<\/p>\n<p data-start=\"749\" data-end=\"823\">MATS: ExtraRange<\/p>\n<p data-start=\"749\" data-end=\"823\">ACPL: Apple CarPlay<\/p>\n<p data-start=\"749\" data-end=\"823\">AFS1: Sistema di illuminazione anteriore adattativo<\/p>\n<p data-start=\"749\" data-end=\"823\">ALOG: Scudo aerografato<\/p>\n<p data-start=\"749\" data-end=\"823\">CALR: pinze freno rosse<\/p>\n<p data-start=\"749\" data-end=\"823\">CEIS: splitter aria laterale in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CEL2: Coperchi motore in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CERB: Rivestimento del bagagliaio posteriore in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CEXD: Diffusore posteriore in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CEXS: Copertura sottoporta in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CFKY: Chiave del veicolo in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CIAD: Bocchetta d'aria per cruscotto in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CIDL: Zona driver in fibra di carbonio + LED<\/p>\n<p data-start=\"749\" data-end=\"823\">CIIP: Copertura dello strumento in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CISK: Piastra di chiusura della soglia esterna in carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CITZ: Parte superiore della console centrale in fibra di carbonio<\/p>\n<p data-start=\"749\" data-end=\"823\">CLDT: dettagli colorati del vano passeggeri<\/p>\n<p data-start=\"749\" data-end=\"823\">CRP1: Tappetini Style1 in pelle\/alcantara<\/p>\n<p>DATR: Inserti per cruscotto in fibra di carbonio<\/p>\n<p>ECAL: Chiamata di emergenza<\/p>\n<p>ELEV: Sollevamento anteriore<\/p>\n<p>EMPH: Cavallino cucito sul poggiatesta<\/p>\n<p>EXAT: Tubi di scarico in titanio<\/p>\n<p>FCWS: Spoiler anteriore in fibra di carbonio<\/p>\n<p>FLMA: Tappetini colorati aggiuntivi con logo<\/p>\n<p>HWCO: Preparazione di MyFerrari Connect HW<\/p>\n<p>IFPD: motivo della bandiera ITA sul cruscotto<\/p>\n<p>INTX: Pelle Extrarange - BIANCA 053108 Pelle<\/p>\n<p>ISSW: Volante<\/p>\n<p>LED: Carb. Fibra. Volante<\/p>\n<p>MIR3: Specchio retrovisore elettrocromico<\/p>\n<p>MNFC: Collettore motore in fibra di carbonio<\/p>\n<p>PAR2: Sensori di parcheggio anteriori e posteriori<\/p>\n<p>PNT0: Colori speciali a 2 strati - NERO STELLATO<\/p>\n<p>RMCF: Ruote in fibra di carbonio<\/p>\n<p>RSCH: Sedili da corsa in fibra di carbonio - Sedili di grandi dimensioni<\/p>\n<p>RSES: Sollevatore di sedili da corsa<\/p>\n<p>SNDH: Sistema HI-FI Premium<\/p>\n<p>SPEC: Specifiche personalizzate<\/p>\n<p>SURR: vista surround<\/p>\n<p>TIWN: Bulloni ruota in titanio<\/p>\n<p>TYMX: Pneumatici Michelin<\/p>\n<p>ZCOA: MyFerrari Connect non attivato<\/p>\n<p data-start=\"749\" data-end=\"823\">","protected":false},"excerpt":{"rendered":"<p>Mi chiamo Martina<\/p>","protected":false},"featured_media":13021,"template":"","meta":[],"automobile":[48],"features":[],"class_list":["post-12990","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","automobile-sf90"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/portfolio\/12990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/media\/13021"}],"wp:attachment":[{"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/media?parent=12990"}],"wp:term":[{"taxonomy":"automobile","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/automobile?post=12990"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/it\/wp-json\/wp\/v2\/features?post=12990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}