{"id":3138,"date":"2021-10-27T16:40:48","date_gmt":"2021-10-27T14:40:48","guid":{"rendered":"https:\/\/www.rossocorsa.es\/?post_type=wpb_portfolio&#038;p=3138"},"modified":"2023-10-05T10:59:59","modified_gmt":"2023-10-05T08:59:59","slug":"ferrari-california-25","status":"publish","type":"portfolio","link":"https:\/\/www.rossocorsa.com\/es\/portfolio\/ferrari-california-25\/","title":{"rendered":"Ferrari California"},"content":{"rendered":"<div class=\"col-sm-12\">\n<div class=\"row\">\n<div class=\"col-sm-4\">El Ferrari California es \u00fanico entre otros superdeportivos. Magn\u00edfico estilo, gran ahorro en combustible, e interior impresionante.<\/div>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-12 col-md-6\">\n<p>Adem\u00e1s, se trata de un coche 100% fiable, con un rendimiento incre\u00edble. Es la m\u00e1xima expresi\u00f3n de clase y deportividad en un veh\u00edculo de carretera. Conducci\u00f3n din\u00e1mica y c\u00f3moda al mismo tiempo.<\/p>\n<p>Exterior Rosso Corsa e interior de impecable dise\u00f1o, en cuero beige claro.<\/p>\n<p>En comparaci\u00f3n con otros convertibles, el techo r\u00edgido retr\u00e1ctil lo hace m\u00e1s pr\u00e1ctico y c\u00f3modo durante todo el a\u00f1o.<\/p>\n<p>Est\u00e1 en perfectas condiciones, nunca tuvo accidentes, y tenemos toda la documentaci\u00f3n y el libro de servicios actualizados. Revision reci\u00e9n hecha y actualmente disponible en nuestro showroom.<\/p>\n<p><strong>Con matr\u00edcula espa\u00f1ola.<\/strong><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Me llamo Giorgina<\/p>","protected":false},"featured_media":8351,"template":"","meta":[],"automobile":[29],"features":[],"class_list":["post-3138","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","automobile-california"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/portfolio\/3138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/media\/8351"}],"wp:attachment":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/media?parent=3138"}],"wp:term":[{"taxonomy":"automobile","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/automobile?post=3138"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/features?post=3138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}