{"id":2843,"date":"2021-01-25T16:03:58","date_gmt":"2021-01-25T15:03:58","guid":{"rendered":"https:\/\/www.rossocorsa.es\/?post_type=wpb_portfolio&#038;p=2843"},"modified":"2024-10-16T10:04:16","modified_gmt":"2024-10-16T08:04:16","slug":"ferrari-f12-berlinetta-7","status":"publish","type":"portfolio","link":"https:\/\/www.rossocorsa.com\/es\/portfolio\/ferrari-f12-berlinetta-7\/","title":{"rendered":"Ferrari F12 Berlinetta"},"content":{"rendered":"<div class=\"col-sm-12\">\n<div class=\"row\">\n<p class=\"col-sm-4\">\u00a1\u00a1Atr\u00e9vete a pisar el acelerador de este F12 Berlinetta y experimentar\u00e1s el verdadero significado de VELOCIDAD!! Este coche deportivo es uno de los m\u00e1s r\u00e1pidos y potentes Ferrari de nuestra era... \u00a1Una bestia que s\u00f3lo pueden dominar los mejores conductores!<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-12 col-md-6\">\n<p>Su arquitectura no es s\u00f3lo magn\u00edfica, sino tambi\u00e9n incre\u00edblemente aerodin\u00e1mica. Est\u00e1 empujada por uno de los m\u00e1s extraordinarios V12 jam\u00e1s creados en Maranello, con 741 cv.<\/p>\n<p>El impresionante rendimiento de este F12 es igualado por un aspecto inspurable: su exterior Nero Daytona y su interior en alc\u00e1ntara negro con costuras en amarillo, \u00a1conviertien este Ferrari en el veh\u00edculo m\u00e1s feroz del panorama!<\/p>\n<p>Matriculado en ESPA\u00d1A.<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Me llamo Vanessa<\/p>","protected":false},"featured_media":7435,"template":"","meta":[],"automobile":[35],"features":[],"class_list":["post-2843","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","automobile-f12"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/portfolio\/2843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/media\/7435"}],"wp:attachment":[{"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/media?parent=2843"}],"wp:term":[{"taxonomy":"automobile","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/automobile?post=2843"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.rossocorsa.com\/es\/wp-json\/wp\/v2\/features?post=2843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}